{"id":125,"count":2,"description":"","link":"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/","name":"vending machine in India","slug":"vending-machine-in-india","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>vending machine in India Archives - Daalchini Blog - Smart Vending Machines in India<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vending machine in India Archives - Daalchini Blog - Smart Vending Machines in India\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/\" \/>\n<meta property=\"og:site_name\" content=\"Daalchini Blog - Smart Vending Machines in India\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Daalchini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/\",\"url\":\"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/\",\"name\":\"vending machine in India Archives - Daalchini Blog - Smart Vending Machines in India\",\"isPartOf\":{\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.daalchini.co.in\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"vending machine in India\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/#website\",\"url\":\"https:\/\/www.daalchini.co.in\/blog\/\",\"name\":\"Daalchini Blog - Smart Vending Machines in India\",\"description\":\"India&#039;s Leading Vending Machine Company\",\"publisher\":{\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.daalchini.co.in\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/#organization\",\"name\":\"Daalchini\",\"url\":\"https:\/\/www.daalchini.co.in\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.daalchini.co.in\/blog\/wp-content\/uploads\/2022\/01\/Daalchini-Logo-512.jpg\",\"contentUrl\":\"https:\/\/www.daalchini.co.in\/blog\/wp-content\/uploads\/2022\/01\/Daalchini-Logo-512.jpg\",\"width\":510,\"height\":510,\"caption\":\"Daalchini\"},\"image\":{\"@id\":\"https:\/\/www.daalchini.co.in\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Daalchini.Hut\",\"https:\/\/x.com\/Daalchini\",\"https:\/\/www.instagram.com\/daalchini_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"vending machine in India Archives - Daalchini Blog - Smart Vending Machines in India","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"vending machine in India Archives - Daalchini Blog - Smart Vending Machines in India","og_url":"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/","og_site_name":"Daalchini Blog - Smart Vending Machines in India","twitter_card":"summary_large_image","twitter_site":"@Daalchini","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/","url":"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/","name":"vending machine in India Archives - Daalchini Blog - Smart Vending Machines in India","isPartOf":{"@id":"https:\/\/www.daalchini.co.in\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.daalchini.co.in\/blog\/tag\/vending-machine-in-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.daalchini.co.in\/blog\/"},{"@type":"ListItem","position":2,"name":"vending machine in India"}]},{"@type":"WebSite","@id":"https:\/\/www.daalchini.co.in\/blog\/#website","url":"https:\/\/www.daalchini.co.in\/blog\/","name":"Daalchini Blog - Smart Vending Machines in India","description":"India&#039;s Leading Vending Machine Company","publisher":{"@id":"https:\/\/www.daalchini.co.in\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.daalchini.co.in\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.daalchini.co.in\/blog\/#organization","name":"Daalchini","url":"https:\/\/www.daalchini.co.in\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.daalchini.co.in\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.daalchini.co.in\/blog\/wp-content\/uploads\/2022\/01\/Daalchini-Logo-512.jpg","contentUrl":"https:\/\/www.daalchini.co.in\/blog\/wp-content\/uploads\/2022\/01\/Daalchini-Logo-512.jpg","width":510,"height":510,"caption":"Daalchini"},"image":{"@id":"https:\/\/www.daalchini.co.in\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Daalchini.Hut","https:\/\/x.com\/Daalchini","https:\/\/www.instagram.com\/daalchini_\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.daalchini.co.in\/blog\/wp-json\/wp\/v2\/tags\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daalchini.co.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.daalchini.co.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.daalchini.co.in\/blog\/wp-json\/wp\/v2\/posts?tags=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}